{"id":931,"date":"2024-11-07T13:47:05","date_gmt":"2024-11-07T13:47:05","guid":{"rendered":"https:\/\/startersites.io\/elementor\/furniture\/?page_id=931"},"modified":"2025-07-22T19:14:34","modified_gmt":"2025-07-22T22:14:34","slug":"sobre-nosotros","status":"publish","type":"page","link":"https:\/\/vlatelie.com\/es\/sobre-nosotros\/","title":{"rendered":"Qui\u00e9nes somos"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"931\" class=\"elementor elementor-931\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-16a6b5a e-flex e-con-boxed e-con e-parent\" data-id=\"16a6b5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-62a866c ct-hero e-flex e-con-boxed e-con e-child\" data-id=\"62a866c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b988174 elementor-widget elementor-widget-heading\" data-id=\"b988174\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qui\u00e9nes somos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-751cb1f elementor-widget elementor-widget-shortcode\" data-id=\"751cb1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f7eba7a e-flex e-con-boxed e-con e-parent\" data-id=\"f7eba7a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-58e5cb4 e-con-full e-flex e-con e-child\" data-id=\"58e5cb4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-79c9aa5 e-con-full e-flex e-con e-child\" data-id=\"79c9aa5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9297bb elementor-widget elementor-widget-icon-box\" data-id=\"f9297bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNuestra misi\u00f3n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAportando bienestar y est\u00e9tica en cada pieza, promoviendo pr\u00e1cticas sostenibles y un toque de elegancia artesanal en tu vida.\n\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c04d0a8 e-con-full e-flex e-con e-child\" data-id=\"c04d0a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a51cb13 elementor-widget elementor-widget-icon-box\" data-id=\"a51cb13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNos encanta lo que hacemos\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEsto se refleja en cada pieza hecha a mano, donde cada detalle se crea con pasi\u00f3n y dedicaci\u00f3n.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b6d56b e-con-full e-flex e-con e-child\" data-id=\"3b6d56b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bfe2dc elementor-widget elementor-widget-icon-box\" data-id=\"7bfe2dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNuestros valores\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSe basan en la calidad, la sostenibilidad y la pasi\u00f3n por la artesan\u00eda, y reflejan nuestro compromiso con la excelencia en cada producto.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59d629b e-flex e-con-boxed e-con e-parent\" data-id=\"59d629b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-16b477c e-con-full e-flex e-con e-child\" data-id=\"16b477c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-28e9212 e-con-full e-flex e-con e-child\" data-id=\"28e9212\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9522735 elementor-widget elementor-widget-image\" data-id=\"9522735\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1067\" height=\"800\" src=\"https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/06\/us-1067x800.jpeg\" class=\"attachment-large size-large wp-image-16606\" alt=\"foto de Leandro y Cintia, Sobre nosotros en VLAteli\u00ea.\" srcset=\"https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/06\/us-1067x800.jpeg 1067w, https:\/\/vlatelie.com\/wp-content\/smush-webp\/2024\/06\/us-800x600.jpeg.webp 800w, https:\/\/vlatelie.com\/wp-content\/smush-webp\/2024\/06\/us-500x375.jpeg.webp 500w, https:\/\/vlatelie.com\/wp-content\/smush-webp\/2024\/06\/us-400x300.jpeg.webp 400w, https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/06\/us-768x576.jpeg 768w, https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/06\/us-16x12.jpeg 16w, https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/06\/us-60x45.jpeg 60w, https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/06\/us-110x83.jpeg 110w, https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/06\/us.jpeg 1280w\" sizes=\"(max-width: 1067px) 100vw, 1067px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0de1236 e-con-full e-flex e-con e-child\" data-id=\"0de1236\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5b8ae7b e-con-full e-flex e-con e-child\" data-id=\"5b8ae7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d7db63 elementor-widget elementor-widget-heading\" data-id=\"1d7db63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Acerca de nuestra tienda<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-361de0e elementor-widget elementor-widget-text-editor\" data-id=\"361de0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a1Bienvenido a nuestra tienda en l\u00ednea, donde la belleza, la curaci\u00f3n y la creatividad se encuentran! Nos apasiona ofrecer productos que no s\u00f3lo adornen tu espacio, sino que tambi\u00e9n aporten paz, energ\u00eda positiva y un toque de elegancia artesanal.<\/p><p>Obtenga m\u00e1s informaci\u00f3n sobre nuestras categor\u00edas de productos y nuestra misi\u00f3n de fomentar el bienestar y la est\u00e9tica en cada pieza.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a760137 e-flex e-con-boxed e-con e-parent\" data-id=\"a760137\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c158b42 e-con-full e-flex e-con e-child\" data-id=\"c158b42\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-029ce56 e-con-full e-flex e-con e-child\" data-id=\"029ce56\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79bac37 elementor-widget elementor-widget-image\" data-id=\"79bac37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"580\" height=\"580\" data-src=\"https:\/\/vlatelie.com\/wp-content\/uploads\/2025\/07\/equipa_vlatelie.webp\" class=\"attachment-large size-large wp-image-18678 lazyload\" alt=\"reuni\u00f3n de equipo con tres mujeres sentadas fuera hablando.\" data-srcset=\"https:\/\/vlatelie.com\/wp-content\/uploads\/2025\/07\/equipa_vlatelie.webp 580w, https:\/\/vlatelie.com\/wp-content\/uploads\/2025\/07\/equipa_vlatelie-300x300.webp 300w, https:\/\/vlatelie.com\/wp-content\/uploads\/2025\/07\/equipa_vlatelie-150x150.webp 150w, https:\/\/vlatelie.com\/wp-content\/uploads\/2025\/07\/equipa_vlatelie-500x500.webp 500w\" data-sizes=\"(max-width: 580px) 100vw, 580px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 580px; --smush-placeholder-aspect-ratio: 580\/580;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-248f4eb e-con-full e-flex e-con e-child\" data-id=\"248f4eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-06aa62d e-con-full e-flex e-con e-child\" data-id=\"06aa62d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-20cbe5d elementor-widget elementor-widget-heading\" data-id=\"20cbe5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nuestro compromiso<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b90c0b elementor-widget elementor-widget-text-editor\" data-id=\"7b90c0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nos comprometemos a ofrecer productos cuidadosamente elaborados a mano, promoviendo pr\u00e1cticas sostenibles y ecol\u00f3gicas en cada fase del proceso. Nuestra misi\u00f3n es ofrecer art\u00edculos que no solo embellecen tu entorno, sino que tambi\u00e9n contribuyen a tu bienestar f\u00edsico, emocional y espiritual.<\/p><p>Cada pieza de nuestra tienda se crea con amor y atenci\u00f3n al detalle, garantizando que recibas productos de alta calidad que son realmente \u00fanicos. Creemos en el poder de la artesan\u00eda y en la energ\u00eda positiva que aporta, y nos sentimos honrados de compartirlo contigo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-98005a0 e-flex e-con-boxed e-con e-parent\" data-id=\"98005a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-79ee9b0 e-con-full e-flex e-con e-child\" data-id=\"79ee9b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02b5349 elementor-widget elementor-widget-heading\" data-id=\"02b5349\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Con\u00e9ctese con nosotros<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5a03d1 elementor-widget elementor-widget-text-editor\" data-id=\"a5a03d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Estamos siempre a su disposici\u00f3n para ayudarle a encontrar el producto perfecto o responder a cualquier pregunta que pueda tener. Con\u00e9ctese con nosotros en las redes sociales o p\u00f3ngase en contacto directamente a trav\u00e9s de nuestra p\u00e1gina de atenci\u00f3n al cliente.<\/p><p>Gracias por visitar nuestra tienda.<\/p><p>Esperamos que encuentre algo que le encante y que aporte alegr\u00eda y paz a su vida cotidiana.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68d88d4 elementor-widget elementor-widget-button\" data-id=\"68d88d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/vlatelie.com\/es\/contactos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 20 13.549\"><path d=\"M19.755 7.402c-.015.018-.02.04-.037.057l-5.806 5.806a.965.965 0 0 1-1.369 0 .967.967 0 0 1 0-1.368l4.155-4.155H.968a.968.968 0 1 1 0-1.935h15.73l-4.155-4.155A.967.967 0 1 1 13.912.284l5.806 5.806c.02.02.028.047.046.069a.957.957 0 0 1 .162.244c.099.237.099.505 0 .743a.96.96 0 0 1-.17.256Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">P\u00f3ngase en contacto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d8c276a e-con-full e-flex e-con e-child\" data-id=\"d8c276a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-859ce58 elementor-widget elementor-widget-image\" data-id=\"859ce58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"954\" height=\"882\" data-src=\"https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/05\/about-us-cta-image.webp\" class=\"attachment-full size-full wp-image-471 lazyload\" alt=\"\" data-srcset=\"https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/05\/about-us-cta-image.webp 954w, https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/05\/about-us-cta-image-324x300.webp 324w, https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/05\/about-us-cta-image-865x800.webp 865w, https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/05\/about-us-cta-image-768x710.webp 768w, https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/05\/about-us-cta-image-13x12.webp 13w, https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/05\/about-us-cta-image-500x462.webp 500w, https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/05\/about-us-cta-image-800x740.webp 800w, https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/05\/about-us-cta-image-150x139.webp 150w\" data-sizes=\"(max-width: 954px) 100vw, 954px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 954px; --smush-placeholder-aspect-ratio: 954\/882;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2b5ba1f e-grid e-con-boxed e-con e-parent\" data-id=\"2b5ba1f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3171a70 e-con-full e-flex e-con e-child\" data-id=\"3171a70\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0343968 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"0343968\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/vlatelie.com\/wp-content\/uploads\/2025\/07\/papelariartigo-300x300.webp\" class=\"attachment-medium size-medium wp-image-18716 lazyload\" alt=\"Mesa de papeler\u00eda con cuaderno personalizado, bol\u00edgrafo decorado y clips de colores, que representan tres trucos cotidianos creativos y \u00fatiles.\" data-srcset=\"https:\/\/vlatelie.com\/wp-content\/uploads\/2025\/07\/papelariartigo-300x300.webp 300w, https:\/\/vlatelie.com\/wp-content\/uploads\/2025\/07\/papelariartigo-150x150.webp 150w, https:\/\/vlatelie.com\/wp-content\/uploads\/2025\/07\/papelariartigo-500x500.webp 500w, https:\/\/vlatelie.com\/wp-content\/uploads\/2025\/07\/papelariartigo.webp 512w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-50f8c8e e-con-full e-flex e-con e-child\" data-id=\"50f8c8e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83030e5 elementor-widget elementor-widget-heading\" data-id=\"83030e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mant\u00e9ngase al d\u00eda de las \u00faltimas noticias sobre artesan\u00eda.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b686126 elementor-widget elementor-widget-text-editor\" data-id=\"b686126\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Consigue 10% de descuento en tu primera compra al registrarte \ud83d\udc8c.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8603285 elementor-widget elementor-widget-shortcode\" data-id=\"8603285\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n\t<div class=\"ct-newsletter-subscribe-shortcode\">\n\t\t\n\t\t\n\t\t<form target=\"_blank\" action=\"#\" method=\"post\"\n\t\t\tdata-provider=\"demo:demolist\"\n\t\t\tclass=\"ct-newsletter-subscribe-form\" data-trp-original-action=\"#\"\n\t\t\t>\n\n\t\t\t<div\n\t\t\t\tclass=\"ct-newsletter-subscribe-form-elements\" data-columns=\"2\">\n\t\t\t\t\n\t\t\t\t<input type=\"email\" name=\"EMAIL\" placeholder=\"Su direcci\u00f3n de correo electr\u00f3nico *\" aria-label=\"Direcci\u00f3n de correo electr\u00f3nico\" required>\n\n\t\t\t\t<button class=\"wp-element-button\">\n\t\t\t\t\tSuscr\u00edbase a\t\t\t\t<\/button>\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t<div class=\"ct-newsletter-subscribe-message\"><\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n\n\t<\/div>\n\n\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>About Us Nossa miss\u00e3o Proporcionar bem-estar e est\u00e9tica em cada pe\u00e7a, promovendo pr\u00e1ticas sustent\u00e1veis e um toque de eleg\u00e2ncia artesanal em sua vida. Amamos o que fazemos Isso se reflete em cada pe\u00e7a artesanal, onde cada detalhe \u00e9 criado com paix\u00e3o e dedica\u00e7\u00e3o. Nossos valores S\u00e3o baseados na qualidade, sustentabilidade e paix\u00e3o pelo artesanato, refletindo [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-931","page","type-page","status-publish","hentry"],"blocksy_meta":{"has_hero_section":"disabled","vertical_spacing_source":"custom","content_area_spacing":"none","styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sobre n\u00f3s - VLAteli\u00ea e Ateli\u00ea da Decora\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vlatelie.com\/es\/sobre-nosotros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sobre n\u00f3s\" \/>\n<meta property=\"og:description\" content=\"About Us Nossa miss\u00e3o Proporcionar bem-estar e est\u00e9tica em cada pe\u00e7a, promovendo pr\u00e1ticas sustent\u00e1veis e um toque de eleg\u00e2ncia artesanal em sua vida. Amamos o que fazemos Isso se reflete em cada pe\u00e7a artesanal, onde cada detalhe \u00e9 criado com paix\u00e3o e dedica\u00e7\u00e3o. Nossos valores S\u00e3o baseados na qualidade, sustentabilidade e paix\u00e3o pelo artesanato, refletindo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vlatelie.com\/es\/sobre-nosotros\/\" \/>\n<meta property=\"og:site_name\" content=\"VLAteli\u00ea e Ateli\u00ea da Decora\u00e7\u00e3o\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ateliedadecora\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-22T22:14:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/06\/us-1067x800.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vlatelie.com\\\/es\\\/sobre-nosotros\\\/\",\"url\":\"https:\\\/\\\/vlatelie.com\\\/es\\\/sobre-nosotros\\\/\",\"name\":\"Sobre n\u00f3s - VLAteli\u00ea e Ateli\u00ea da Decora\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vlatelie.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vlatelie.com\\\/es\\\/sobre-nosotros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vlatelie.com\\\/es\\\/sobre-nosotros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vlatelie.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/us-1067x800.jpeg\",\"datePublished\":\"2024-11-07T13:47:05+00:00\",\"dateModified\":\"2025-07-22T22:14:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vlatelie.com\\\/es\\\/sobre-nosotros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vlatelie.com\\\/es\\\/sobre-nosotros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vlatelie.com\\\/es\\\/sobre-nosotros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vlatelie.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/us-1067x800.jpeg\",\"contentUrl\":\"https:\\\/\\\/vlatelie.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/us-1067x800.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vlatelie.com\\\/es\\\/sobre-nosotros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/vlatelie.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sobre n\u00f3s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vlatelie.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/vlatelie.com\\\/fr\\\/\",\"name\":\"VLAteli\u00ea e Ateli\u00ea da Decora\u00e7\u00e3o\",\"description\":\"Onde cada pe\u00e7a conta uma hist\u00f3ria\",\"publisher\":{\"@id\":\"https:\\\/\\\/vlatelie.com\\\/fr\\\/#organization\"},\"alternateName\":\"VLAteli\u00ea\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vlatelie.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vlatelie.com\\\/fr\\\/#organization\",\"name\":\"VLAteli\u00ea e Ateli\u00ea da Decora\u00e7\u00e3o\",\"url\":\"https:\\\/\\\/vlatelie.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vlatelie.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vlatelie.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo_vlatelie_pink.svg\",\"contentUrl\":\"https:\\\/\\\/vlatelie.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo_vlatelie_pink.svg\",\"width\":377,\"height\":127,\"caption\":\"VLAteli\u00ea e Ateli\u00ea da Decora\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/vlatelie.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ateliedadecora\",\"https:\\\/\\\/www.instagram.com\\\/ateliedadecora\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/vlatelie.com\\\/es\\\/politica-de-devolucion-y-reembolso\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sobre - VLAteli\u00ea y Ateli\u00ea da Decora\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vlatelie.com\/es\/sobre-nosotros\/","og_locale":"es_ES","og_type":"article","og_title":"Sobre n\u00f3s","og_description":"About Us Nossa miss\u00e3o Proporcionar bem-estar e est\u00e9tica em cada pe\u00e7a, promovendo pr\u00e1ticas sustent\u00e1veis e um toque de eleg\u00e2ncia artesanal em sua vida. Amamos o que fazemos Isso se reflete em cada pe\u00e7a artesanal, onde cada detalhe \u00e9 criado com paix\u00e3o e dedica\u00e7\u00e3o. Nossos valores S\u00e3o baseados na qualidade, sustentabilidade e paix\u00e3o pelo artesanato, refletindo [&hellip;]","og_url":"https:\/\/vlatelie.com\/es\/sobre-nosotros\/","og_site_name":"VLAteli\u00ea e Ateli\u00ea da Decora\u00e7\u00e3o","article_publisher":"https:\/\/www.facebook.com\/ateliedadecora","article_modified_time":"2025-07-22T22:14:34+00:00","og_image":[{"url":"https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/06\/us-1067x800.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vlatelie.com\/es\/sobre-nosotros\/","url":"https:\/\/vlatelie.com\/es\/sobre-nosotros\/","name":"Sobre - VLAteli\u00ea y Ateli\u00ea da Decora\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/vlatelie.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vlatelie.com\/es\/sobre-nosotros\/#primaryimage"},"image":{"@id":"https:\/\/vlatelie.com\/es\/sobre-nosotros\/#primaryimage"},"thumbnailUrl":"https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/06\/us-1067x800.jpeg","datePublished":"2024-11-07T13:47:05+00:00","dateModified":"2025-07-22T22:14:34+00:00","breadcrumb":{"@id":"https:\/\/vlatelie.com\/es\/sobre-nosotros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vlatelie.com\/es\/sobre-nosotros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vlatelie.com\/es\/sobre-nosotros\/#primaryimage","url":"https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/06\/us-1067x800.jpeg","contentUrl":"https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/06\/us-1067x800.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/vlatelie.com\/es\/sobre-nosotros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/vlatelie.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Sobre n\u00f3s"}]},{"@type":"WebSite","@id":"https:\/\/vlatelie.com\/fr\/#website","url":"https:\/\/vlatelie.com\/fr\/","name":"VLAteli\u00ea y Ateli\u00ea da Decora\u00e7\u00e3o","description":"Donde cada pieza cuenta una historia","publisher":{"@id":"https:\/\/vlatelie.com\/fr\/#organization"},"alternateName":"VLAteli\u00ea","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vlatelie.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vlatelie.com\/fr\/#organization","name":"VLAteli\u00ea y Ateli\u00ea da Decora\u00e7\u00e3o","url":"https:\/\/vlatelie.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vlatelie.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/03\/logo_vlatelie_pink.svg","contentUrl":"https:\/\/vlatelie.com\/wp-content\/uploads\/2024\/03\/logo_vlatelie_pink.svg","width":377,"height":127,"caption":"VLAteli\u00ea e Ateli\u00ea da Decora\u00e7\u00e3o"},"image":{"@id":"https:\/\/vlatelie.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ateliedadecora","https:\/\/www.instagram.com\/ateliedadecora"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/vlatelie.com\/es\/politica-de-devolucion-y-reembolso\/"}}]}},"_links":{"self":[{"href":"https:\/\/vlatelie.com\/es\/wp-json\/wp\/v2\/pages\/931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vlatelie.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vlatelie.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vlatelie.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vlatelie.com\/es\/wp-json\/wp\/v2\/comments?post=931"}],"version-history":[{"count":0,"href":"https:\/\/vlatelie.com\/es\/wp-json\/wp\/v2\/pages\/931\/revisions"}],"wp:attachment":[{"href":"https:\/\/vlatelie.com\/es\/wp-json\/wp\/v2\/media?parent=931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}